{"id":825,"count":44,"description":"","link":"https:\/\/www.cde.ual.es\/en\/tag\/biology\/","name":"Biology","slug":"biology","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biology archivos | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cde.ual.es\/en\/tag\/biology\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biology archivos | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cde.ual.es\/en\/tag\/biology\/\" \/>\n<meta property=\"og:site_name\" content=\"CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cdeualmeria\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/tag\\\/biology\\\/\",\"url\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/tag\\\/biology\\\/\",\"name\":\"Biology archivos | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/tag\\\/biology\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/tag\\\/biology\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biology\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#website\",\"url\":\"https:\\\/\\\/www.cde.ual.es\\\/\",\"name\":\"CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda\",\"description\":\"Centro de Documentaci\u00f3n Europea de la Universidad de Almer\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#organization\"},\"alternateName\":\"CDE Almer\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cde.ual.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#organization\",\"name\":\"Centro de Documentaci\u00f3n Europea de Almer\u00eda\",\"url\":\"https:\\\/\\\/www.cde.ual.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cde-logo-3.png\",\"contentUrl\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cde-logo-3.png\",\"width\":1400,\"height\":300,\"caption\":\"Centro de Documentaci\u00f3n Europea de Almer\u00eda\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cdeuniversidadalmeria\\\/\",\"https:\\\/\\\/x.com\\\/cdeualmeria\",\"https:\\\/\\\/www.tiktok.com\\\/@cdealmeria\",\"https:\\\/\\\/www.instagram.com\\\/cdealmeria\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/cde-almera-812b26a9\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biology archivos | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cde.ual.es\/en\/tag\/biology\/","og_locale":"en_US","og_type":"article","og_title":"Biology archivos | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","og_url":"https:\/\/www.cde.ual.es\/en\/tag\/biology\/","og_site_name":"CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","twitter_card":"summary_large_image","twitter_site":"@cdeualmeria","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.cde.ual.es\/en\/tag\/biology\/","url":"https:\/\/www.cde.ual.es\/en\/tag\/biology\/","name":"Biology archivos | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","isPartOf":{"@id":"https:\/\/www.cde.ual.es\/#website"},"breadcrumb":{"@id":"https:\/\/www.cde.ual.es\/en\/tag\/biology\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cde.ual.es\/en\/tag\/biology\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cde.ual.es\/en\/"},{"@type":"ListItem","position":2,"name":"Biology"}]},{"@type":"WebSite","@id":"https:\/\/www.cde.ual.es\/#website","url":"https:\/\/www.cde.ual.es\/","name":"CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","description":"Centro de Documentaci\u00f3n Europea de la Universidad de Almer\u00eda","publisher":{"@id":"https:\/\/www.cde.ual.es\/#organization"},"alternateName":"CDE Almer\u00eda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cde.ual.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.cde.ual.es\/#organization","name":"Centro de Documentaci\u00f3n Europea de Almer\u00eda","url":"https:\/\/www.cde.ual.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cde.ual.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2025\/07\/cde-logo-3.png","contentUrl":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2025\/07\/cde-logo-3.png","width":1400,"height":300,"caption":"Centro de Documentaci\u00f3n Europea de Almer\u00eda"},"image":{"@id":"https:\/\/www.cde.ual.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cdeuniversidadalmeria\/","https:\/\/x.com\/cdeualmeria","https:\/\/www.tiktok.com\/@cdealmeria","https:\/\/www.instagram.com\/cdealmeria\/","https:\/\/www.linkedin.com\/in\/cde-almera-812b26a9\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/tags\/825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/posts?tags=825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}