{"id":5667,"date":"2018-06-07T09:02:07","date_gmt":"2018-06-07T07:02:07","guid":{"rendered":"http:\/\/www.cde.ual.es\/?p=5667"},"modified":"2018-06-07T09:03:32","modified_gmt":"2018-06-07T07:03:32","slug":"oferta-de-practicas-erasmus-en-reino-unido","status":"publish","type":"post","link":"https:\/\/www.cde.ual.es\/en\/oferta-de-practicas-erasmus-en-reino-unido\/","title":{"rendered":"Oferta de Pr\u00e1cticas ERASMUS + en Reino Unido"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/www.cde.ual.es\/wp-content\/uploads\/2018\/06\/ERASMUS-.jpg\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-5675\" src=\"http:\/\/www.cde.ual.es\/wp-content\/uploads\/2018\/06\/ERASMUS--300x140.jpg\" alt=\"\" width=\"300\" height=\"140\" srcset=\"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2018\/06\/ERASMUS--300x140.jpg 300w, https:\/\/www.cde.ual.es\/wp-content\/uploads\/2018\/06\/ERASMUS-.jpg 328w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><em><strong>Erasmus+<\/strong><\/em> presta ayudas para que los estudiantes de grado, licenciatura y m\u00e1ster matriculados en instituciones de educaci\u00f3n superior de los pa\u00edses del programa y los estudiantes de doctorado puedan realizar periodos de formaci\u00f3n pr\u00e1ctica en el extranjero. Tambi\u00e9n pueden participar los estudiantes reci\u00e9n titulados.<\/p>\n<p>Gracias a estas pr\u00e1cticas en el extranjero, los participantes pueden mejorar sus competencias comunicativas, ling\u00fc\u00edsticas e interculturales, adquirir aptitudes no t\u00e9cnicas muy valoradas en el mercado laboral y desarrollar una mentalidad m\u00e1s emprendedora. M\u00e1s sobre las\u00a0<a href=\"http:\/\/ec.europa.eu\/education\/library\/study\/2014\/erasmus-impact_en.pdf\">ventajas de un intercambio en el extranjero<\/a>.<\/p>\n<p>Te contamos la oferta de pr\u00e1cticas\u00a0en el extranjero ERASMUS + en el REINO UNIDO :<\/p>\n<h3><strong>Destinatarios:<\/strong><\/h3>\n<p>Estudiantes matriculados en \u00faltimo a\u00f1o (o reci\u00e9n titulados hace menos de 12 meses) en alguna de las siguientes titulaciones en el curso acad\u00e9mico 2017\/2018:<\/p>\n<ul>\n<li>Grado en Ingenier\u00eda Agr\u00edcola (UAL)<\/li>\n<li>M\u00e1ster en Horticultura Mediterr\u00e1nea bajo Invernadero (UAL)<\/li>\n<li>M\u00e1ster en Ingenier\u00eda Agron\u00f3mica (UAL)<\/li>\n<li>M\u00e1ster en Derecho de la Empresa y la Actividad Agroalimentaria (UAL)<\/li>\n<li>M\u00e1ster en Biotecnologia Industrial y Agroalimentaria (UAL)<\/li>\n<li>Cualquier otro Grado \/ M\u00e1ster donde el alumno haya adquirido conocimientos de agricultura, log\u00edstica y\/o ciencias de la alimentaci\u00f3n.<\/li>\n<\/ul>\n<h3><strong>Requisitos:<\/strong><\/h3>\n<ul>\n<li>Poseer la nacionalidad de uno de los pa\u00edses participantes en el Programa Erasmus o estar reconocido por el pa\u00eds en el que reside como refugiado, ap\u00e1trida o residente permanente.<\/li>\n<li>Estar matriculado en alguna de las titulaciones anteriormente citadas en la Universidad de Almer\u00eda en el curso 2017\/2018.<\/li>\n<li>Tener el 50 % de los cr\u00e9ditos superados (en el caso de los grados).<\/li>\n<li>Disponer de un certificado oficial m\u00ednimo de B1 de ingl\u00e9s (listado de certificados aceptados en Anexo I en la web del programa).<\/li>\n<li>Alumnos que no hayan participado en el programa Leonardo da Vinci con anterioridad.<\/li>\n<\/ul>\n<p>Aquellos solicitantes que hayan realizado otras becas de movilidad bajo el programa Erasmus, no podr\u00e1n superar los 12 meses de movilidad total (sumando Erasmus de Estudio y Erasmus de Pr\u00e1cticas, en el caso de haberlo realizado en anteriores convocatorias). Ejemplo: un estudiante que haya realizado 10 meses de Erasmus de Estudio, solamente tendr\u00e1 disponibles 2 meses de pr\u00e1cticas. Un estudiante que haya realizado 9 meses de Erasmus de Estudio y 3 de Erasmus de Pr\u00e1cticas en convocatorias anteriores, ya no puede solicitar esta oferta.<\/p>\n<h3><strong>Lugar<\/strong>:<\/h3>\n<p>Surbiton \u2013 Inglaterra (Reino Unido).<\/p>\n<h3><strong>Duraci\u00f3n<\/strong>:<\/h3>\n<p>2 a 3 meses<\/p>\n<h3><strong>N\u00ba de plazas<\/strong>:<\/h3>\n<p>1<\/p>\n<h3><strong>Inicio:<\/strong><\/h3>\n<p>Junio 2018.<\/p>\n<h3><strong>Descripci\u00f3n de la oferta:<\/strong><\/h3>\n<p>Apoyo a administrativo de ventas y para ello debe tener conocimientos de log\u00edstica\/alimentaci\u00f3n. Empresa de exportaci\u00f3n y ventas de verduras y frutas, con tama\u00f1o de 40 trabajadores.<\/p>\n<h3><strong>Perfil del participante que solicita la empresa:\u00a0<\/strong><\/h3>\n<ul>\n<li>Conocimientos de Ingl\u00e9s (B2-C1) Hablado y escrito.<\/li>\n<li>Experiencia o conocimientos de agricultura, log\u00edstica, ciencias de la alimentaci\u00f3n o ingenier\u00eda.<\/li>\n<li>Paquete Office<\/li>\n<\/ul>\n<h3><strong>Remuneraci\u00f3n:\u00a0<\/strong><\/h3>\n<p>Subvenci\u00f3n Erasmus Pr\u00e1cticas: 400\u20ac\/mes.<\/p>\n<p><strong><u>Fecha l\u00edmite recepci\u00f3n de solicitudes:<\/u><\/strong><\/p>\n<p><u> 08\/06\/2018<\/u><\/p>\n<p><strong>Interesados: Enviar un email a\u00a0<a href=\"mailto:pextran@fundacionual.es\">pextran@fundacionual.es<\/a>\u00a0con CV Europass + Carta de motivaci\u00f3n en ingl\u00e9s (no se aceptar\u00e1 la documentaci\u00f3n en espa\u00f1ol). Indicar en Asunto: \u201cReferencia de la oferta (Ver en el t\u00edtulo)\u00a0 +\u00a0 NOMBRE Y APELLIDOS\u201d<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erasmus+ presta ayudas para que los estudiantes de grado, licenciatura y m\u00e1ster matriculados en instituciones de educaci\u00f3n superior de los pa\u00edses del programa y los estudiantes de doctorado puedan realizar periodos de formaci\u00f3n pr\u00e1ctica en el extranjero. Tambi\u00e9n pueden participar los estudiantes reci\u00e9n titulados. Gracias a estas pr\u00e1cticas en el extranjero, los participantes pueden mejorar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5677,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_monsterinsights_skip_tracking":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[96],"tags":[138,154],"class_list":["post-5667","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-ue","tag-empleo","tag-movilidad","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oferta de Pr\u00e1cticas ERASMUS + en Reino Unido | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cde.ual.es\/oferta-de-practicas-erasmus-en-reino-unido\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oferta de Pr\u00e1cticas ERASMUS + en Reino Unido | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda\" \/>\n<meta property=\"og:description\" content=\"Erasmus+ presta ayudas para que los estudiantes de grado, licenciatura y m\u00e1ster matriculados en instituciones de educaci\u00f3n superior de los pa\u00edses del programa y los estudiantes de doctorado puedan realizar periodos de formaci\u00f3n pr\u00e1ctica en el extranjero. Tambi\u00e9n pueden participar los estudiantes reci\u00e9n titulados. Gracias a estas pr\u00e1cticas en el extranjero, los participantes pueden mejorar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cde.ual.es\/oferta-de-practicas-erasmus-en-reino-unido\/\" \/>\n<meta property=\"og:site_name\" content=\"CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cdeuniversidadalmeria\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-07T07:02:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-07T07:03:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2018\/06\/Reino-Unido.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"509\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AdminCDE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdeualmeria\" \/>\n<meta name=\"twitter:site\" content=\"@cdeualmeria\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"AdminCDE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/oferta-de-practicas-erasmus-en-reino-unido\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/oferta-de-practicas-erasmus-en-reino-unido\\\/\"},\"author\":{\"name\":\"AdminCDE\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#\\\/schema\\\/person\\\/13895e824f15237b9d9b0152b5f65d80\"},\"headline\":\"Oferta de Pr\u00e1cticas ERASMUS + en Reino Unido\",\"datePublished\":\"2018-06-07T07:02:07+00:00\",\"dateModified\":\"2018-06-07T07:03:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/oferta-de-practicas-erasmus-en-reino-unido\\\/\"},\"wordCount\":539,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/oferta-de-practicas-erasmus-en-reino-unido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/Reino-Unido.jpg\",\"keywords\":[\"Empleo\",\"Movilidad\"],\"articleSection\":[\"Noticias UE\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cde.ual.es\\\/oferta-de-practicas-erasmus-en-reino-unido\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/oferta-de-practicas-erasmus-en-reino-unido\\\/\",\"url\":\"https:\\\/\\\/www.cde.ual.es\\\/oferta-de-practicas-erasmus-en-reino-unido\\\/\",\"name\":\"Oferta de Pr\u00e1cticas ERASMUS + en Reino Unido | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/oferta-de-practicas-erasmus-en-reino-unido\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/oferta-de-practicas-erasmus-en-reino-unido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/Reino-Unido.jpg\",\"datePublished\":\"2018-06-07T07:02:07+00:00\",\"dateModified\":\"2018-06-07T07:03:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/oferta-de-practicas-erasmus-en-reino-unido\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cde.ual.es\\\/oferta-de-practicas-erasmus-en-reino-unido\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/oferta-de-practicas-erasmus-en-reino-unido\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/Reino-Unido.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/Reino-Unido.jpg\",\"width\":509,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/oferta-de-practicas-erasmus-en-reino-unido\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias UE\",\"item\":\"https:\\\/\\\/www.cde.ual.es\\\/category\\\/noticias-ue\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Oferta de Pr\u00e1cticas ERASMUS + en Reino Unido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#website\",\"url\":\"https:\\\/\\\/www.cde.ual.es\\\/\",\"name\":\"CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda\",\"description\":\"Centro de Documentaci\u00f3n Europea de la Universidad de Almer\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#organization\"},\"alternateName\":\"CDE Almer\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cde.ual.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#organization\",\"name\":\"Centro de Documentaci\u00f3n Europea de Almer\u00eda\",\"url\":\"https:\\\/\\\/www.cde.ual.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cde-logo-3.png\",\"contentUrl\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cde-logo-3.png\",\"width\":1400,\"height\":300,\"caption\":\"Centro de Documentaci\u00f3n Europea de Almer\u00eda\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cdeuniversidadalmeria\\\/\",\"https:\\\/\\\/x.com\\\/cdeualmeria\",\"https:\\\/\\\/www.tiktok.com\\\/@cdealmeria\",\"https:\\\/\\\/www.instagram.com\\\/cdealmeria\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/cde-almera-812b26a9\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#\\\/schema\\\/person\\\/13895e824f15237b9d9b0152b5f65d80\",\"name\":\"AdminCDE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a72d038d371f995cd13706fac32274b7952a52e8fb0a84b5f80c85426f2a98a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a72d038d371f995cd13706fac32274b7952a52e8fb0a84b5f80c85426f2a98a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a72d038d371f995cd13706fac32274b7952a52e8fb0a84b5f80c85426f2a98a8?s=96&d=mm&r=g\",\"caption\":\"AdminCDE\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oferta de Pr\u00e1cticas ERASMUS + en Reino Unido | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cde.ual.es\/oferta-de-practicas-erasmus-en-reino-unido\/","og_locale":"en_US","og_type":"article","og_title":"Oferta de Pr\u00e1cticas ERASMUS + en Reino Unido | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","og_description":"Erasmus+ presta ayudas para que los estudiantes de grado, licenciatura y m\u00e1ster matriculados en instituciones de educaci\u00f3n superior de los pa\u00edses del programa y los estudiantes de doctorado puedan realizar periodos de formaci\u00f3n pr\u00e1ctica en el extranjero. Tambi\u00e9n pueden participar los estudiantes reci\u00e9n titulados. Gracias a estas pr\u00e1cticas en el extranjero, los participantes pueden mejorar [&hellip;]","og_url":"https:\/\/www.cde.ual.es\/oferta-de-practicas-erasmus-en-reino-unido\/","og_site_name":"CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","article_publisher":"https:\/\/www.facebook.com\/cdeuniversidadalmeria\/","article_published_time":"2018-06-07T07:02:07+00:00","article_modified_time":"2018-06-07T07:03:32+00:00","og_image":[{"width":509,"height":340,"url":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2018\/06\/Reino-Unido.jpg","type":"image\/jpeg"}],"author":"AdminCDE","twitter_card":"summary_large_image","twitter_creator":"@cdeualmeria","twitter_site":"@cdeualmeria","twitter_misc":{"Written by":"AdminCDE","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cde.ual.es\/oferta-de-practicas-erasmus-en-reino-unido\/#article","isPartOf":{"@id":"https:\/\/www.cde.ual.es\/oferta-de-practicas-erasmus-en-reino-unido\/"},"author":{"name":"AdminCDE","@id":"https:\/\/www.cde.ual.es\/#\/schema\/person\/13895e824f15237b9d9b0152b5f65d80"},"headline":"Oferta de Pr\u00e1cticas ERASMUS + en Reino Unido","datePublished":"2018-06-07T07:02:07+00:00","dateModified":"2018-06-07T07:03:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cde.ual.es\/oferta-de-practicas-erasmus-en-reino-unido\/"},"wordCount":539,"commentCount":0,"publisher":{"@id":"https:\/\/www.cde.ual.es\/#organization"},"image":{"@id":"https:\/\/www.cde.ual.es\/oferta-de-practicas-erasmus-en-reino-unido\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2018\/06\/Reino-Unido.jpg","keywords":["Empleo","Movilidad"],"articleSection":["Noticias UE"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cde.ual.es\/oferta-de-practicas-erasmus-en-reino-unido\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cde.ual.es\/oferta-de-practicas-erasmus-en-reino-unido\/","url":"https:\/\/www.cde.ual.es\/oferta-de-practicas-erasmus-en-reino-unido\/","name":"Oferta de Pr\u00e1cticas ERASMUS + en Reino Unido | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","isPartOf":{"@id":"https:\/\/www.cde.ual.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cde.ual.es\/oferta-de-practicas-erasmus-en-reino-unido\/#primaryimage"},"image":{"@id":"https:\/\/www.cde.ual.es\/oferta-de-practicas-erasmus-en-reino-unido\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2018\/06\/Reino-Unido.jpg","datePublished":"2018-06-07T07:02:07+00:00","dateModified":"2018-06-07T07:03:32+00:00","breadcrumb":{"@id":"https:\/\/www.cde.ual.es\/oferta-de-practicas-erasmus-en-reino-unido\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cde.ual.es\/oferta-de-practicas-erasmus-en-reino-unido\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cde.ual.es\/oferta-de-practicas-erasmus-en-reino-unido\/#primaryimage","url":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2018\/06\/Reino-Unido.jpg","contentUrl":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2018\/06\/Reino-Unido.jpg","width":509,"height":340},{"@type":"BreadcrumbList","@id":"https:\/\/www.cde.ual.es\/oferta-de-practicas-erasmus-en-reino-unido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cde.ual.es\/en\/"},{"@type":"ListItem","position":2,"name":"Noticias UE","item":"https:\/\/www.cde.ual.es\/category\/noticias-ue\/"},{"@type":"ListItem","position":3,"name":"Oferta de Pr\u00e1cticas ERASMUS + en Reino Unido"}]},{"@type":"WebSite","@id":"https:\/\/www.cde.ual.es\/#website","url":"https:\/\/www.cde.ual.es\/","name":"CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","description":"Centro de Documentaci\u00f3n Europea de la Universidad de Almer\u00eda","publisher":{"@id":"https:\/\/www.cde.ual.es\/#organization"},"alternateName":"CDE Almer\u00eda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cde.ual.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.cde.ual.es\/#organization","name":"Centro de Documentaci\u00f3n Europea de Almer\u00eda","url":"https:\/\/www.cde.ual.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cde.ual.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2025\/07\/cde-logo-3.png","contentUrl":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2025\/07\/cde-logo-3.png","width":1400,"height":300,"caption":"Centro de Documentaci\u00f3n Europea de Almer\u00eda"},"image":{"@id":"https:\/\/www.cde.ual.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cdeuniversidadalmeria\/","https:\/\/x.com\/cdeualmeria","https:\/\/www.tiktok.com\/@cdealmeria","https:\/\/www.instagram.com\/cdealmeria\/","https:\/\/www.linkedin.com\/in\/cde-almera-812b26a9\/"]},{"@type":"Person","@id":"https:\/\/www.cde.ual.es\/#\/schema\/person\/13895e824f15237b9d9b0152b5f65d80","name":"AdminCDE","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/a72d038d371f995cd13706fac32274b7952a52e8fb0a84b5f80c85426f2a98a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a72d038d371f995cd13706fac32274b7952a52e8fb0a84b5f80c85426f2a98a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a72d038d371f995cd13706fac32274b7952a52e8fb0a84b5f80c85426f2a98a8?s=96&d=mm&r=g","caption":"AdminCDE"}}]}},"_links":{"self":[{"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/posts\/5667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/comments?post=5667"}],"version-history":[{"count":0,"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/posts\/5667\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/media\/5677"}],"wp:attachment":[{"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/media?parent=5667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/categories?post=5667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/tags?post=5667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}