{"id":31440,"date":"2019-12-17T03:00:42","date_gmt":"2019-12-17T02:00:42","guid":{"rendered":"https:\/\/www.cde.ual.es\/?p=31440"},"modified":"2019-12-17T08:52:46","modified_gmt":"2019-12-17T07:52:46","slug":"programa-de-radio-europa-contigo-no-26","status":"publish","type":"post","link":"https:\/\/www.cde.ual.es\/en\/programa-de-radio-europa-contigo-no-26\/","title":{"rendered":"Programa de radio &#8220;Europa Contigo&#8221; No 26"},"content":{"rendered":"<p><a href=\"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2019\/10\/20191011_114233.jpg\"><img decoding=\"async\" class=\"size-medium wp-image-27271 aligncenter\" src=\"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2019\/10\/20191011_114233-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2019\/10\/20191011_114233-300x225.jpg 300w, https:\/\/www.cde.ual.es\/wp-content\/uploads\/2019\/10\/20191011_114233-768x576.jpg 768w, https:\/\/www.cde.ual.es\/wp-content\/uploads\/2019\/10\/20191011_114233-1024x768.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><em><strong>El Centro de Documentaci\u00f3n Europea de Almer\u00eda abre las puertas de Europa a la comunidad universitaria y a la ciudadan\u00eda en general con el programa de radio \u00abEuropa Contigo\u00bb .\u00a0El programa se emite cada semana con un recorrido por la actualidad de Europa, con las \u00faltimas noticias, lecturas recomendadas, mediateca y actividades m\u00e1s destacadas.\u00a0<\/strong><\/em><\/p>\n<p>En la edici\u00f3n n\u00famero 26 se hace\u00a0\u00a0un repaso a las<a href=\"https:\/\/www.cde.ual.es\/preferencias-de-nuestros-usuarios-lo-mas-visto-en-noviembre-2019\/\"> preferencias de nuestros usuarios durante el mes de noviembre<\/a>, tanto en espa\u00f1ol como en ingl\u00e9s.<\/p>\n<p>Tras esta secci\u00f3n, se abordan las noticias m\u00e1s relevantes y el recientemente publicado Bolet\u00edn de I +I.<\/p>\n<p>El Bolet\u00edn Informativo de Investigaci\u00f3n e Innovaci\u00f3n resume toda la actividad de la Uni\u00f3n Europea en el campo de I+I en los meses de octubre y noviembre. El bolet\u00edn est\u00e1 estructurado en Noticias y Actualidad; Convocatorias; Estad\u00edsticas e Infograf\u00edas;\u00a0 Documentaci\u00f3n; y finalmente, Revistas y Mediateca.<\/p>\n<p>En el programa de radio te contamos m\u00e1s sobre este bolet\u00edn, solo tienes que pinchar\u00a0<a href=\"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2019\/12\/europacontigox26.mp3\">aqu\u00ed<\/a> para escucharlo.<\/p>\n<h3>M\u00e1s informaci\u00f3n<\/h3>\n<p><a href=\"https:\/\/www.cde.ual.es\/programa-de-radio-europa-contigo\/\">Programas de Radio &#8220;Europa Contigo&#8221;<\/a><\/p>\n<h4 style=\"text-align: center;\"><em>No dudes en enviarnos aquellas preguntas que desees que resolvamos en \u00abel aire\u00bb<\/em><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>El Centro de Documentaci\u00f3n Europea de Almer\u00eda abre las puertas de Europa a la comunidad universitaria y a la ciudadan\u00eda en general con el programa de radio \u00abEuropa Contigo\u00bb .\u00a0El programa se emite cada semana con un recorrido por la actualidad de Europa, con las \u00faltimas noticias, lecturas recomendadas, mediateca y actividades m\u00e1s destacadas.\u00a0 En [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27271,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[114],"tags":[],"class_list":["post-31440","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actividades","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Programa de radio &quot;Europa Contigo&quot; No 26 | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cde.ual.es\/en\/programa-de-radio-europa-contigo-no-26\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programa de radio &quot;Europa Contigo&quot; No 26 | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda\" \/>\n<meta property=\"og:description\" content=\"El Centro de Documentaci\u00f3n Europea de Almer\u00eda abre las puertas de Europa a la comunidad universitaria y a la ciudadan\u00eda en general con el programa de radio \u00abEuropa Contigo\u00bb .\u00a0El programa se emite cada semana con un recorrido por la actualidad de Europa, con las \u00faltimas noticias, lecturas recomendadas, mediateca y actividades m\u00e1s destacadas.\u00a0 En [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cde.ual.es\/en\/programa-de-radio-europa-contigo-no-26\/\" \/>\n<meta property=\"og:site_name\" content=\"CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cdeuniversidadalmeria\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-17T02:00:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-17T07:52:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2019\/10\/20191011_114233.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4032\" \/>\n\t<meta property=\"og:image:height\" content=\"3024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AdminCDE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdeualmeria\" \/>\n<meta name=\"twitter:site\" content=\"@cdeualmeria\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"AdminCDE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/programa-de-radio-europa-contigo-no-26\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/programa-de-radio-europa-contigo-no-26\\\/\"},\"author\":{\"name\":\"AdminCDE\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#\\\/schema\\\/person\\\/13895e824f15237b9d9b0152b5f65d80\"},\"headline\":\"Programa de radio &#8220;Europa Contigo&#8221; No 26\",\"datePublished\":\"2019-12-17T02:00:42+00:00\",\"dateModified\":\"2019-12-17T07:52:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/programa-de-radio-europa-contigo-no-26\\\/\"},\"wordCount\":209,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/programa-de-radio-europa-contigo-no-26\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/20191011_114233.jpg\",\"articleSection\":[\"Actividades\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/programa-de-radio-europa-contigo-no-26\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/programa-de-radio-europa-contigo-no-26\\\/\",\"url\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/programa-de-radio-europa-contigo-no-26\\\/\",\"name\":\"Programa de radio \\\"Europa Contigo\\\" No 26 | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/programa-de-radio-europa-contigo-no-26\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/programa-de-radio-europa-contigo-no-26\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/20191011_114233.jpg\",\"datePublished\":\"2019-12-17T02:00:42+00:00\",\"dateModified\":\"2019-12-17T07:52:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/programa-de-radio-europa-contigo-no-26\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/programa-de-radio-europa-contigo-no-26\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/programa-de-radio-europa-contigo-no-26\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/20191011_114233.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/20191011_114233.jpg\",\"width\":4032,\"height\":3024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/programa-de-radio-europa-contigo-no-26\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Activities\",\"item\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/category\\\/activities\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Programa de radio &#8220;Europa Contigo&#8221; No 26\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#website\",\"url\":\"https:\\\/\\\/www.cde.ual.es\\\/\",\"name\":\"CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda\",\"description\":\"Centro de Documentaci\u00f3n Europea de la Universidad de Almer\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#organization\"},\"alternateName\":\"CDE Almer\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cde.ual.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#organization\",\"name\":\"Centro de Documentaci\u00f3n Europea de Almer\u00eda\",\"url\":\"https:\\\/\\\/www.cde.ual.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cde-logo-3.png\",\"contentUrl\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cde-logo-3.png\",\"width\":1400,\"height\":300,\"caption\":\"Centro de Documentaci\u00f3n Europea de Almer\u00eda\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cdeuniversidadalmeria\\\/\",\"https:\\\/\\\/x.com\\\/cdeualmeria\",\"https:\\\/\\\/www.tiktok.com\\\/@cdealmeria\",\"https:\\\/\\\/www.instagram.com\\\/cdealmeria\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/cde-almera-812b26a9\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#\\\/schema\\\/person\\\/13895e824f15237b9d9b0152b5f65d80\",\"name\":\"AdminCDE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a72d038d371f995cd13706fac32274b7952a52e8fb0a84b5f80c85426f2a98a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a72d038d371f995cd13706fac32274b7952a52e8fb0a84b5f80c85426f2a98a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a72d038d371f995cd13706fac32274b7952a52e8fb0a84b5f80c85426f2a98a8?s=96&d=mm&r=g\",\"caption\":\"AdminCDE\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programa de radio \"Europa Contigo\" No 26 | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cde.ual.es\/en\/programa-de-radio-europa-contigo-no-26\/","og_locale":"en_US","og_type":"article","og_title":"Programa de radio \"Europa Contigo\" No 26 | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","og_description":"El Centro de Documentaci\u00f3n Europea de Almer\u00eda abre las puertas de Europa a la comunidad universitaria y a la ciudadan\u00eda en general con el programa de radio \u00abEuropa Contigo\u00bb .\u00a0El programa se emite cada semana con un recorrido por la actualidad de Europa, con las \u00faltimas noticias, lecturas recomendadas, mediateca y actividades m\u00e1s destacadas.\u00a0 En [&hellip;]","og_url":"https:\/\/www.cde.ual.es\/en\/programa-de-radio-europa-contigo-no-26\/","og_site_name":"CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","article_publisher":"https:\/\/www.facebook.com\/cdeuniversidadalmeria\/","article_published_time":"2019-12-17T02:00:42+00:00","article_modified_time":"2019-12-17T07:52:46+00:00","og_image":[{"width":4032,"height":3024,"url":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2019\/10\/20191011_114233.jpg","type":"image\/jpeg"}],"author":"AdminCDE","twitter_card":"summary_large_image","twitter_creator":"@cdeualmeria","twitter_site":"@cdeualmeria","twitter_misc":{"Written by":"AdminCDE","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cde.ual.es\/en\/programa-de-radio-europa-contigo-no-26\/#article","isPartOf":{"@id":"https:\/\/www.cde.ual.es\/en\/programa-de-radio-europa-contigo-no-26\/"},"author":{"name":"AdminCDE","@id":"https:\/\/www.cde.ual.es\/#\/schema\/person\/13895e824f15237b9d9b0152b5f65d80"},"headline":"Programa de radio &#8220;Europa Contigo&#8221; No 26","datePublished":"2019-12-17T02:00:42+00:00","dateModified":"2019-12-17T07:52:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cde.ual.es\/en\/programa-de-radio-europa-contigo-no-26\/"},"wordCount":209,"commentCount":0,"publisher":{"@id":"https:\/\/www.cde.ual.es\/#organization"},"image":{"@id":"https:\/\/www.cde.ual.es\/en\/programa-de-radio-europa-contigo-no-26\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2019\/10\/20191011_114233.jpg","articleSection":["Actividades"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cde.ual.es\/en\/programa-de-radio-europa-contigo-no-26\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cde.ual.es\/en\/programa-de-radio-europa-contigo-no-26\/","url":"https:\/\/www.cde.ual.es\/en\/programa-de-radio-europa-contigo-no-26\/","name":"Programa de radio \"Europa Contigo\" No 26 | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","isPartOf":{"@id":"https:\/\/www.cde.ual.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cde.ual.es\/en\/programa-de-radio-europa-contigo-no-26\/#primaryimage"},"image":{"@id":"https:\/\/www.cde.ual.es\/en\/programa-de-radio-europa-contigo-no-26\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2019\/10\/20191011_114233.jpg","datePublished":"2019-12-17T02:00:42+00:00","dateModified":"2019-12-17T07:52:46+00:00","breadcrumb":{"@id":"https:\/\/www.cde.ual.es\/en\/programa-de-radio-europa-contigo-no-26\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cde.ual.es\/en\/programa-de-radio-europa-contigo-no-26\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cde.ual.es\/en\/programa-de-radio-europa-contigo-no-26\/#primaryimage","url":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2019\/10\/20191011_114233.jpg","contentUrl":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2019\/10\/20191011_114233.jpg","width":4032,"height":3024},{"@type":"BreadcrumbList","@id":"https:\/\/www.cde.ual.es\/en\/programa-de-radio-europa-contigo-no-26\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cde.ual.es\/en\/"},{"@type":"ListItem","position":2,"name":"Activities","item":"https:\/\/www.cde.ual.es\/en\/category\/activities\/"},{"@type":"ListItem","position":3,"name":"Programa de radio &#8220;Europa Contigo&#8221; No 26"}]},{"@type":"WebSite","@id":"https:\/\/www.cde.ual.es\/#website","url":"https:\/\/www.cde.ual.es\/","name":"CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","description":"Centro de Documentaci\u00f3n Europea de la Universidad de Almer\u00eda","publisher":{"@id":"https:\/\/www.cde.ual.es\/#organization"},"alternateName":"CDE Almer\u00eda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cde.ual.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.cde.ual.es\/#organization","name":"Centro de Documentaci\u00f3n Europea de Almer\u00eda","url":"https:\/\/www.cde.ual.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cde.ual.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2025\/07\/cde-logo-3.png","contentUrl":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2025\/07\/cde-logo-3.png","width":1400,"height":300,"caption":"Centro de Documentaci\u00f3n Europea de Almer\u00eda"},"image":{"@id":"https:\/\/www.cde.ual.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cdeuniversidadalmeria\/","https:\/\/x.com\/cdeualmeria","https:\/\/www.tiktok.com\/@cdealmeria","https:\/\/www.instagram.com\/cdealmeria\/","https:\/\/www.linkedin.com\/in\/cde-almera-812b26a9\/"]},{"@type":"Person","@id":"https:\/\/www.cde.ual.es\/#\/schema\/person\/13895e824f15237b9d9b0152b5f65d80","name":"AdminCDE","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/a72d038d371f995cd13706fac32274b7952a52e8fb0a84b5f80c85426f2a98a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a72d038d371f995cd13706fac32274b7952a52e8fb0a84b5f80c85426f2a98a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a72d038d371f995cd13706fac32274b7952a52e8fb0a84b5f80c85426f2a98a8?s=96&d=mm&r=g","caption":"AdminCDE"}}]}},"_links":{"self":[{"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/posts\/31440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/comments?post=31440"}],"version-history":[{"count":0,"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/posts\/31440\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/media\/27271"}],"wp:attachment":[{"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/media?parent=31440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/categories?post=31440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/tags?post=31440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}