{"id":109136,"date":"2022-06-02T13:21:51","date_gmt":"2022-06-02T11:21:51","guid":{"rendered":"https:\/\/www.cde.ual.es\/?p=109136"},"modified":"2022-06-02T13:53:53","modified_gmt":"2022-06-02T11:53:53","slug":"el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales","status":"publish","type":"post","link":"https:\/\/www.cde.ual.es\/en\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\/","title":{"rendered":"El procedimiento prejudicial \u2014 Un di\u00e1logo con los tribunales nacionales"},"content":{"rendered":"<p>T\u00edtulo: El procedimiento prejudicial \u2014 Un di\u00e1logo con los tribunales nacionales<\/p>\n<p>Autor: Tribunal de Justicia de la Uni\u00f3n Europea<\/p>\n<p>Duraci\u00f3n: 01:41<\/p>\n<p>Fecha de Publicaci\u00f3n: 02-07-21<\/p>\n<p>Resumen: Las peticiones de decisi\u00f3n prejudicial son un elemento clave del sistema jur\u00eddico de la Uni\u00f3n Europea. Cuando los tribunales nacionales aplican directamente el Derecho de la Uni\u00f3n, este procedimiento les permite consultar al Tribunal de Justicia sobre c\u00f3mo deben interpretarse las normas antes de resolver un asunto. Conozca mejor c\u00f3mo funciona este procedimiento y el di\u00e1logo que se establece entre los tribunales nacionales y el Tribunal de Justicia de la Uni\u00f3n Europea.<\/p>\n<p><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/yKpb2GfvFZk\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>T\u00edtulo: El procedimiento prejudicial \u2014 Un di\u00e1logo con los tribunales nacionales Autor: Tribunal de Justicia de la Uni\u00f3n Europea Duraci\u00f3n: 01:41 Fecha de Publicaci\u00f3n: 02-07-21 Resumen: Las peticiones de decisi\u00f3n prejudicial son un elemento clave del sistema jur\u00eddico de la Uni\u00f3n Europea. Cuando los tribunales nacionales aplican directamente el Derecho de la Uni\u00f3n, este procedimiento [&hellip;]<\/p>\n","protected":false},"author":101011,"featured_media":109145,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[122,115],"tags":[],"class_list":{"0":"post-109136","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mediateca-derecho","8":"category-repositorio-mediateca","9":"entry"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El procedimiento prejudicial \u2014 Un di\u00e1logo con los tribunales nacionales | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cde.ual.es\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El procedimiento prejudicial \u2014 Un di\u00e1logo con los tribunales nacionales | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda\" \/>\n<meta property=\"og:description\" content=\"T\u00edtulo: El procedimiento prejudicial \u2014 Un di\u00e1logo con los tribunales nacionales Autor: Tribunal de Justicia de la Uni\u00f3n Europea Duraci\u00f3n: 01:41 Fecha de Publicaci\u00f3n: 02-07-21 Resumen: Las peticiones de decisi\u00f3n prejudicial son un elemento clave del sistema jur\u00eddico de la Uni\u00f3n Europea. Cuando los tribunales nacionales aplican directamente el Derecho de la Uni\u00f3n, este procedimiento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cde.ual.es\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\/\" \/>\n<meta property=\"og:site_name\" content=\"CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cdeuniversidadalmeria\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-02T11:21:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-02T11:53:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2022\/06\/mediateca-11.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1269\" \/>\n\t<meta property=\"og:image:height\" content=\"713\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"BECA 2 CDE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cdeualmeria\" \/>\n<meta name=\"twitter:site\" content=\"@cdeualmeria\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"BECA 2 CDE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\\\/\"},\"author\":{\"name\":\"BECA 2 CDE\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#\\\/schema\\\/person\\\/9662c5031c15e7db2d4b64d401d71f1f\"},\"headline\":\"El procedimiento prejudicial \u2014 Un di\u00e1logo con los tribunales nacionales\",\"datePublished\":\"2022-06-02T11:21:51+00:00\",\"dateModified\":\"2022-06-02T11:53:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\\\/\"},\"wordCount\":120,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/mediateca-11.png\",\"articleSection\":[\"Mediateca - Derecho\",\"Repositorio Mediateca\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cde.ual.es\\\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\\\/\",\"url\":\"https:\\\/\\\/www.cde.ual.es\\\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\\\/\",\"name\":\"El procedimiento prejudicial \u2014 Un di\u00e1logo con los tribunales nacionales | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/mediateca-11.png\",\"datePublished\":\"2022-06-02T11:21:51+00:00\",\"dateModified\":\"2022-06-02T11:53:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cde.ual.es\\\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/mediateca-11.png\",\"contentUrl\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/mediateca-11.png\",\"width\":1269,\"height\":713},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cde.ual.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Repositorio Mediateca\",\"item\":\"https:\\\/\\\/www.cde.ual.es\\\/category\\\/repositorio-mediateca\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mediateca - Derecho\",\"item\":\"https:\\\/\\\/www.cde.ual.es\\\/category\\\/repositorio-mediateca\\\/mediateca-derecho\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"El procedimiento prejudicial \u2014 Un di\u00e1logo con los tribunales nacionales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#website\",\"url\":\"https:\\\/\\\/www.cde.ual.es\\\/\",\"name\":\"CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda\",\"description\":\"Centro de Documentaci\u00f3n Europea de la Universidad de Almer\u00eda\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#organization\"},\"alternateName\":\"CDE Almer\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cde.ual.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#organization\",\"name\":\"Centro de Documentaci\u00f3n Europea de Almer\u00eda\",\"url\":\"https:\\\/\\\/www.cde.ual.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cde-logo-3.png\",\"contentUrl\":\"https:\\\/\\\/www.cde.ual.es\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cde-logo-3.png\",\"width\":1400,\"height\":300,\"caption\":\"Centro de Documentaci\u00f3n Europea de Almer\u00eda\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cdeuniversidadalmeria\\\/\",\"https:\\\/\\\/x.com\\\/cdeualmeria\",\"https:\\\/\\\/www.tiktok.com\\\/@cdealmeria\",\"https:\\\/\\\/www.instagram.com\\\/cdealmeria\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/cde-almera-812b26a9\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cde.ual.es\\\/#\\\/schema\\\/person\\\/9662c5031c15e7db2d4b64d401d71f1f\",\"name\":\"BECA 2 CDE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35a481bbc04bbd90e91bdfa3b0b5541036c222a49b9ad37b6889a2afcb5311a5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35a481bbc04bbd90e91bdfa3b0b5541036c222a49b9ad37b6889a2afcb5311a5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35a481bbc04bbd90e91bdfa3b0b5541036c222a49b9ad37b6889a2afcb5311a5?s=96&d=mm&r=g\",\"caption\":\"BECA 2 CDE\"},\"sameAs\":[\"http:\\\/\\\/www.cdealmeria.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El procedimiento prejudicial \u2014 Un di\u00e1logo con los tribunales nacionales | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cde.ual.es\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\/","og_locale":"en_US","og_type":"article","og_title":"El procedimiento prejudicial \u2014 Un di\u00e1logo con los tribunales nacionales | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","og_description":"T\u00edtulo: El procedimiento prejudicial \u2014 Un di\u00e1logo con los tribunales nacionales Autor: Tribunal de Justicia de la Uni\u00f3n Europea Duraci\u00f3n: 01:41 Fecha de Publicaci\u00f3n: 02-07-21 Resumen: Las peticiones de decisi\u00f3n prejudicial son un elemento clave del sistema jur\u00eddico de la Uni\u00f3n Europea. Cuando los tribunales nacionales aplican directamente el Derecho de la Uni\u00f3n, este procedimiento [&hellip;]","og_url":"https:\/\/www.cde.ual.es\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\/","og_site_name":"CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","article_publisher":"https:\/\/www.facebook.com\/cdeuniversidadalmeria\/","article_published_time":"2022-06-02T11:21:51+00:00","article_modified_time":"2022-06-02T11:53:53+00:00","og_image":[{"width":1269,"height":713,"url":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2022\/06\/mediateca-11.png","type":"image\/png"}],"author":"BECA 2 CDE","twitter_card":"summary_large_image","twitter_creator":"@cdeualmeria","twitter_site":"@cdeualmeria","twitter_misc":{"Written by":"BECA 2 CDE","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cde.ual.es\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\/#article","isPartOf":{"@id":"https:\/\/www.cde.ual.es\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\/"},"author":{"name":"BECA 2 CDE","@id":"https:\/\/www.cde.ual.es\/#\/schema\/person\/9662c5031c15e7db2d4b64d401d71f1f"},"headline":"El procedimiento prejudicial \u2014 Un di\u00e1logo con los tribunales nacionales","datePublished":"2022-06-02T11:21:51+00:00","dateModified":"2022-06-02T11:53:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cde.ual.es\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\/"},"wordCount":120,"commentCount":0,"publisher":{"@id":"https:\/\/www.cde.ual.es\/#organization"},"image":{"@id":"https:\/\/www.cde.ual.es\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2022\/06\/mediateca-11.png","articleSection":["Mediateca - Derecho","Repositorio Mediateca"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cde.ual.es\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cde.ual.es\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\/","url":"https:\/\/www.cde.ual.es\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\/","name":"El procedimiento prejudicial \u2014 Un di\u00e1logo con los tribunales nacionales | CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","isPartOf":{"@id":"https:\/\/www.cde.ual.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cde.ual.es\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\/#primaryimage"},"image":{"@id":"https:\/\/www.cde.ual.es\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2022\/06\/mediateca-11.png","datePublished":"2022-06-02T11:21:51+00:00","dateModified":"2022-06-02T11:53:53+00:00","breadcrumb":{"@id":"https:\/\/www.cde.ual.es\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cde.ual.es\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cde.ual.es\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\/#primaryimage","url":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2022\/06\/mediateca-11.png","contentUrl":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2022\/06\/mediateca-11.png","width":1269,"height":713},{"@type":"BreadcrumbList","@id":"https:\/\/www.cde.ual.es\/el-procedimiento-prejudicial-un-dialogo-con-los-tribunales-nacionales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cde.ual.es\/en\/"},{"@type":"ListItem","position":2,"name":"Repositorio Mediateca","item":"https:\/\/www.cde.ual.es\/category\/repositorio-mediateca\/"},{"@type":"ListItem","position":3,"name":"Mediateca - Derecho","item":"https:\/\/www.cde.ual.es\/category\/repositorio-mediateca\/mediateca-derecho\/"},{"@type":"ListItem","position":4,"name":"El procedimiento prejudicial \u2014 Un di\u00e1logo con los tribunales nacionales"}]},{"@type":"WebSite","@id":"https:\/\/www.cde.ual.es\/#website","url":"https:\/\/www.cde.ual.es\/","name":"CDE Almer\u00eda - Centro de Documentaci\u00f3n Europea - Universidad de Almer\u00eda","description":"Centro de Documentaci\u00f3n Europea de la Universidad de Almer\u00eda","publisher":{"@id":"https:\/\/www.cde.ual.es\/#organization"},"alternateName":"CDE Almer\u00eda","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cde.ual.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.cde.ual.es\/#organization","name":"Centro de Documentaci\u00f3n Europea de Almer\u00eda","url":"https:\/\/www.cde.ual.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.cde.ual.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2025\/07\/cde-logo-3.png","contentUrl":"https:\/\/www.cde.ual.es\/wp-content\/uploads\/2025\/07\/cde-logo-3.png","width":1400,"height":300,"caption":"Centro de Documentaci\u00f3n Europea de Almer\u00eda"},"image":{"@id":"https:\/\/www.cde.ual.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cdeuniversidadalmeria\/","https:\/\/x.com\/cdeualmeria","https:\/\/www.tiktok.com\/@cdealmeria","https:\/\/www.instagram.com\/cdealmeria\/","https:\/\/www.linkedin.com\/in\/cde-almera-812b26a9\/"]},{"@type":"Person","@id":"https:\/\/www.cde.ual.es\/#\/schema\/person\/9662c5031c15e7db2d4b64d401d71f1f","name":"BECA 2 CDE","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/35a481bbc04bbd90e91bdfa3b0b5541036c222a49b9ad37b6889a2afcb5311a5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35a481bbc04bbd90e91bdfa3b0b5541036c222a49b9ad37b6889a2afcb5311a5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35a481bbc04bbd90e91bdfa3b0b5541036c222a49b9ad37b6889a2afcb5311a5?s=96&d=mm&r=g","caption":"BECA 2 CDE"},"sameAs":["http:\/\/www.cdealmeria.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/posts\/109136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/users\/101011"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/comments?post=109136"}],"version-history":[{"count":1,"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/posts\/109136\/revisions"}],"predecessor-version":[{"id":109147,"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/posts\/109136\/revisions\/109147"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/media\/109145"}],"wp:attachment":[{"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/media?parent=109136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/categories?post=109136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cde.ual.es\/en\/wp-json\/wp\/v2\/tags?post=109136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}